{"id":11153,"date":"2023-05-03T15:29:19","date_gmt":"2023-05-03T15:29:19","guid":{"rendered":"http:\/\/nchasia.com\/en-au\/?p=11153"},"modified":"2024-03-13T04:47:45","modified_gmt":"2024-03-13T04:47:45","slug":"nch-video_bluestreak","status":"publish","type":"post","link":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/","title":{"rendered":"NCH video | Drain Cleaner | Blue Streak"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":12136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,21,18,22],"tags":[758],"class_list":["post-11153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all","category-facility-maintenance","category-industrial-maintenance","category-maintenance","tag-video","article_type-videos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eliminate foul odors | dissolve accumulated waste| drain cleaner<\/title>\n<meta name=\"description\" content=\"Learn more on Blue Streak, Eliminate foul odors | dissolve accumulated waste| drain cleaner\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eliminate foul odors | dissolve accumulated waste| drain cleaner\" \/>\n<meta property=\"og:description\" content=\"Learn more on Blue Streak, Eliminate foul odors | dissolve accumulated waste| drain cleaner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/\" \/>\n<meta property=\"og:site_name\" content=\"NCH Australia\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-03T15:29:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-13T04:47:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nchasia.com\/en-au\/wp-content\/resources\/sites\/8\/2023\/05\/teaser-bluestreak.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"860\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"HeeYoung\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"HeeYoung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/\"},\"author\":{\"name\":\"HeeYoung\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#\\\/schema\\\/person\\\/eec7504a06c62ec6e45e9dfc3764c671\"},\"headline\":\"NCH video | Drain Cleaner | Blue Streak\",\"datePublished\":\"2023-05-03T15:29:19+00:00\",\"dateModified\":\"2024-03-13T04:47:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/wp-content\\\/resources\\\/sites\\\/8\\\/2023\\\/05\\\/teaser-bluestreak.jpg\",\"keywords\":[\"Video\"],\"articleSection\":[\"All\",\"Facility Maintenance\",\"Industrial Maintenance\",\"Maintenance\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/\",\"url\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/\",\"name\":\"Eliminate foul odors | dissolve accumulated waste| drain cleaner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/wp-content\\\/resources\\\/sites\\\/8\\\/2023\\\/05\\\/teaser-bluestreak.jpg\",\"datePublished\":\"2023-05-03T15:29:19+00:00\",\"dateModified\":\"2024-03-13T04:47:45+00:00\",\"description\":\"Learn more on Blue Streak, Eliminate foul odors | dissolve accumulated waste| drain cleaner\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/wp-content\\\/resources\\\/sites\\\/8\\\/2023\\\/05\\\/teaser-bluestreak.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/wp-content\\\/resources\\\/sites\\\/8\\\/2023\\\/05\\\/teaser-bluestreak.jpg\",\"width\":960,\"height\":860},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/nch-video_bluestreak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\\/\",\"item\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NCH video | Drain Cleaner | Blue Streak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#website\",\"url\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/\",\"name\":\"NCH Australia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#organization\",\"name\":\"NCH Australia\",\"url\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/wp-content\\\/resources\\\/sites\\\/8\\\/2023\\\/01\\\/NCH-Established-1919-Logo2-01@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/wp-content\\\/resources\\\/sites\\\/8\\\/2023\\\/01\\\/NCH-Established-1919-Logo2-01@2x.png\",\"width\":196,\"height\":240,\"caption\":\"NCH Australia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/#\\\/schema\\\/person\\\/eec7504a06c62ec6e45e9dfc3764c671\",\"name\":\"HeeYoung\",\"url\":\"https:\\\/\\\/www.nchasia.com\\\/en-au\\\/author\\\/heeyoung1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eliminate foul odors | dissolve accumulated waste| drain cleaner","description":"Learn more on Blue Streak, Eliminate foul odors | dissolve accumulated waste| drain cleaner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/","og_locale":"en_US","og_type":"article","og_title":"Eliminate foul odors | dissolve accumulated waste| drain cleaner","og_description":"Learn more on Blue Streak, Eliminate foul odors | dissolve accumulated waste| drain cleaner","og_url":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/","og_site_name":"NCH Australia","article_published_time":"2023-05-03T15:29:19+00:00","article_modified_time":"2024-03-13T04:47:45+00:00","og_image":[{"width":960,"height":860,"url":"https:\/\/www.nchasia.com\/en-au\/wp-content\/resources\/sites\/8\/2023\/05\/teaser-bluestreak.jpg","type":"image\/jpeg"}],"author":"HeeYoung","twitter_card":"summary_large_image","twitter_misc":{"Written by":"HeeYoung"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/#article","isPartOf":{"@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/"},"author":{"name":"HeeYoung","@id":"https:\/\/www.nchasia.com\/en-au\/#\/schema\/person\/eec7504a06c62ec6e45e9dfc3764c671"},"headline":"NCH video | Drain Cleaner | Blue Streak","datePublished":"2023-05-03T15:29:19+00:00","dateModified":"2024-03-13T04:47:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/"},"wordCount":6,"publisher":{"@id":"https:\/\/www.nchasia.com\/en-au\/#organization"},"image":{"@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nchasia.com\/en-au\/wp-content\/resources\/sites\/8\/2023\/05\/teaser-bluestreak.jpg","keywords":["Video"],"articleSection":["All","Facility Maintenance","Industrial Maintenance","Maintenance"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/","url":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/","name":"Eliminate foul odors | dissolve accumulated waste| drain cleaner","isPartOf":{"@id":"https:\/\/www.nchasia.com\/en-au\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/#primaryimage"},"image":{"@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nchasia.com\/en-au\/wp-content\/resources\/sites\/8\/2023\/05\/teaser-bluestreak.jpg","datePublished":"2023-05-03T15:29:19+00:00","dateModified":"2024-03-13T04:47:45+00:00","description":"Learn more on Blue Streak, Eliminate foul odors | dissolve accumulated waste| drain cleaner","breadcrumb":{"@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/#primaryimage","url":"https:\/\/www.nchasia.com\/en-au\/wp-content\/resources\/sites\/8\/2023\/05\/teaser-bluestreak.jpg","contentUrl":"https:\/\/www.nchasia.com\/en-au\/wp-content\/resources\/sites\/8\/2023\/05\/teaser-bluestreak.jpg","width":960,"height":860},{"@type":"BreadcrumbList","@id":"https:\/\/www.nchasia.com\/en-au\/nch-video_bluestreak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\/","item":"https:\/\/www.nchasia.com\/en-au\/"},{"@type":"ListItem","position":2,"name":"NCH video | Drain Cleaner | Blue Streak"}]},{"@type":"WebSite","@id":"https:\/\/www.nchasia.com\/en-au\/#website","url":"https:\/\/www.nchasia.com\/en-au\/","name":"NCH Australia","description":"","publisher":{"@id":"https:\/\/www.nchasia.com\/en-au\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nchasia.com\/en-au\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nchasia.com\/en-au\/#organization","name":"NCH Australia","url":"https:\/\/www.nchasia.com\/en-au\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nchasia.com\/en-au\/#\/schema\/logo\/image\/","url":"https:\/\/www.nchasia.com\/en-au\/wp-content\/resources\/sites\/8\/2023\/01\/NCH-Established-1919-Logo2-01@2x.png","contentUrl":"https:\/\/www.nchasia.com\/en-au\/wp-content\/resources\/sites\/8\/2023\/01\/NCH-Established-1919-Logo2-01@2x.png","width":196,"height":240,"caption":"NCH Australia"},"image":{"@id":"https:\/\/www.nchasia.com\/en-au\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nchasia.com\/en-au\/#\/schema\/person\/eec7504a06c62ec6e45e9dfc3764c671","name":"HeeYoung","url":"https:\/\/www.nchasia.com\/en-au\/author\/heeyoung1\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/posts\/11153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/comments?post=11153"}],"version-history":[{"count":5,"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/posts\/11153\/revisions"}],"predecessor-version":[{"id":12990,"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/posts\/11153\/revisions\/12990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/media\/12136"}],"wp:attachment":[{"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/media?parent=11153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/categories?post=11153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nchasia.com\/en-au\/wp-json\/wp\/v2\/tags?post=11153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}